{"id":1597,"date":"2019-10-11T02:41:38","date_gmt":"2019-10-11T02:41:38","guid":{"rendered":"http:\/\/franciscaclaret.com\/wordpress\/?p=1597"},"modified":"2019-10-11T02:41:38","modified_gmt":"2019-10-11T02:41:38","slug":"mural-jackson-pollock","status":"publish","type":"post","link":"http:\/\/franciscaclaret.com\/wordpress\/2019\/10\/11\/mural-jackson-pollock\/","title":{"rendered":"Mural &#8211; Jackson Pollock"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-1598\" src=\"http:\/\/franciscaclaret.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_2094-1024x768.jpg\" alt=\"\" width=\"840\" height=\"630\" srcset=\"http:\/\/franciscaclaret.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_2094-1024x768.jpg 1024w, http:\/\/franciscaclaret.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_2094-300x225.jpg 300w, http:\/\/franciscaclaret.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_2094-768x576.jpg 768w, http:\/\/franciscaclaret.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_2094-1200x900.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>Pollock got a commission to create a mural for the entry to Peggy Guggenheim&#8217;s new townhouse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pollock got a commission to create a mural for the entry to Peggy Guggenheim&#8217;s new townhouse.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"_links":{"self":[{"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/posts\/1597"}],"collection":[{"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/comments?post=1597"}],"version-history":[{"count":1,"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/posts\/1597\/revisions"}],"predecessor-version":[{"id":1599,"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/posts\/1597\/revisions\/1599"}],"wp:attachment":[{"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/media?parent=1597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/categories?post=1597"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/franciscaclaret.com\/wordpress\/wp-json\/wp\/v2\/tags?post=1597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}